{"id":1164,"date":"2023-05-18T10:48:36","date_gmt":"2023-05-18T13:48:36","guid":{"rendered":"http:\/\/lacicor.eba.ufmg.br\/antecipa\/?p=1164"},"modified":"2024-09-07T19:18:59","modified_gmt":"2024-09-07T22:18:59","slug":"ntpr-uma-trajetoria-de-40-anos","status":"publish","type":"post","link":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/2023\/05\/18\/ntpr-uma-trajetoria-de-40-anos\/","title":{"rendered":"NTPR &#8211; UMA TRAJET\u00d3RIA DE 40 ANOS"},"content":{"rendered":"\n<p>Temos a grata satisfa\u00e7\u00e3o de comunicar que em 2023 o\u00a0 N\u00facleo de Tecnologia da Preserva\u00e7\u00e3o e da Restaura\u00e7\u00e3o (NTPR) fundado pelo Professor\u00a0M\u00e1rio Mendon\u00e7a de Oliveira &#8211;\u00a0 Primeiro Associado Benem\u00e9rito da ANTECIPA &#8211; completa 40 anos!<\/p>\n\n\n\n<p>Viabilizado por acordo de coopera\u00e7\u00e3o entre a UFBA e o Instituto do Patrim\u00f4nio Hist\u00f3rico e Art\u00edstico Nacional (IPHAN), o NTPR foi o primeiro laborat\u00f3rio brasileiro de pesquisa cient\u00edfica na \u00e1rea de Tecnologia da Conserva\u00e7\u00e3o e do Restauro e atende, at\u00e9 hoje, alunos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o da UFBA, al\u00e9m de estudantes e profissionais de outras institui\u00e7\u00f5es e regi\u00f5es do Brasil.<br\/><\/p>\n\n\n\n<p>Em comemora\u00e7\u00e3o a este importante marco cient\u00edfico e institucional, compartilhamos o convite para o evento <strong>NTPR 40 ANOS<\/strong>: abertura de uma s\u00e9rie de palestras e oficinas que ocorrer\u00e3o ao longo do ano de 2023 e que contar\u00e3o com professores e pesquisadores parceiros de v\u00e1rios estados brasileiros.<br\/><\/p>\n\n\n\n<p><strong>Data da Abertura: 24\/05\/2023<br\/><\/strong><\/p>\n\n\n\n<p><strong>Hora: 9h<br\/><\/strong><\/p>\n\n\n\n<p><strong>Local: Mastaba da FAUFBA<br\/><\/strong><strong>CONTATOS: Entre em contato pelo Tel:\u00a0(71)3283-9858\u00a0ou, se preferir, mande um e-mail para\u00a0ntpr@ufba.br<\/strong><\/p>\n\n\n\n<p><a href=\"http:\/\/www.ntpr.ufba.br\/40anos.html\">http:\/\/www.ntpr.ufba.br\/40anos.html<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1079\" height=\"1083\" src=\"http:\/\/lacicor.eba.ufmg.br\/antecipa\/wp-content\/uploads\/2023\/05\/ntpr.jpeg\" alt=\"\" class=\"wp-image-1165\"\/><\/figure>\n\n\n\n<p><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Temos a grata satisfa\u00e7\u00e3o de comunicar que em 2023 o\u00a0 N\u00facleo de Tecnologia da Preserva\u00e7\u00e3o e da Restaura\u00e7\u00e3o (NTPR) fundado pelo Professor\u00a0M\u00e1rio Mendon\u00e7a de Oliveira &#8211;\u00a0 Primeiro Associado Benem\u00e9rito da &#8230;<\/p>\n","protected":false},"author":1,"featured_media":1165,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anuncios"],"_links":{"self":[{"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/posts\/1164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/comments?post=1164"}],"version-history":[{"count":3,"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/posts\/1164\/revisions"}],"predecessor-version":[{"id":1169,"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/posts\/1164\/revisions\/1169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/media\/1165"}],"wp:attachment":[{"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/media?parent=1164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/categories?post=1164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacicor.eba.ufmg.br\/antecipa\/index.php\/wp-json\/wp\/v2\/tags?post=1164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}